{"id":6063,"date":"2026-05-14T12:42:15","date_gmt":"2026-05-14T10:42:15","guid":{"rendered":"https:\/\/monteagudo.info\/web\/?p=6063"},"modified":"2026-05-14T12:42:15","modified_gmt":"2026-05-14T10:42:15","slug":"diamuseos-castillejo-2026","status":"publish","type":"post","link":"https:\/\/monteagudo.info\/web\/diamuseos-castillejo-2026\/","title":{"rendered":"El Castillejo se suma como espacio cultural en el d\u00eda de los Museos"},"content":{"rendered":"<p align=\"justify\">\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6065\" src=\"https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos.jpg\" alt=\"\" width=\"1584\" height=\"672\" srcset=\"https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos.jpg 1584w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos-300x127.jpg 300w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos-1024x434.jpg 1024w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos-768x326.jpg 768w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos-1536x652.jpg 1536w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/bannerdiamuseos-555x235.jpg 555w\" sizes=\"auto, (max-width: 1584px) 100vw, 1584px\" \/><\/p>\n<p align=\"justify\">El Palacio Ibn Mardanis o Castillejo que se suma como escenario cultural con motivo del d\u00eda internacional de los museos, y acoger\u00e1 el s\u00e1bado de 17:30 a 21:00h una jornada llena de historia, cultura y diversi\u00f3n para sumergirse en la \u00e9poca de Ibn Mardanis, el c\u00e9lebre Rey Lobo, y descubrir el esplendor de la Murcia Andalus\u00ed a trav\u00e9s de una programaci\u00f3n especial dise\u00f1ada para todos los p\u00fablicos.<\/p>\n<p data-end=\"772\" data-start=\"408\">El evento tendr\u00e1 lugar en la tarde del s\u00e1bado 16 de mayo de 2026 en el Palacio de Ibn Mardanis, recientemente restaurado y convertido en uno de los enclaves patrimoniales m\u00e1s singulares del municipio. Durante toda la tarde, los visitantes podr\u00e1n recorrer libremente el recinto, participar en actividades familiares y conocer de cerca el legado del Rey Lobo en un entorno \u00fanico.<\/p>\n<p data-end=\"1016\" data-start=\"774\">La programaci\u00f3n incluye puertas abiertas y visitas guiadas, campamento infantil de oficios medievales, exposici\u00f3n de instrumentos hist\u00f3ricos, muestra y vuelo de aves rapaces y la actividad participativa \u201cMusicuentos en la corte del Rey Lobo\u201d.<\/p>\n<p data-end=\"1184\" data-start=\"1018\">Una propuesta cultural gratuita y pensada para todos los p\u00fablicos, que combina divulgaci\u00f3n, entretenimiento y patrimonio en el coraz\u00f3n de las Fortalezas del Rey Lobo.<\/p>\n<h4><span style=\"color: #993300;\"><strong>Actividades<\/strong><\/span><\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Puertas abiertas y visitas guiadas:<\/strong>\u00a0Recorre el Palacio de Ibn Mardanis y descubre la historia y restauraci\u00f3n del Castillejo mediante visitas guiadas cada hora a cargo de arque\u00f3logos especializados.<\/li>\n<li><strong>Campamento infantil \u00abLos Constructores del Para\u00edso\u00bb<\/strong>: Talleres participativos donde los ni\u00f1os elaborar\u00e1n y decorar\u00e1n instrumentos inspirados en la m\u00fasica medieval andalus\u00ed, que podr\u00e1n utilizar posteriormente durante el \u00abMusicuento en la Corte del Rey Lobo\u00bb<\/li>\n<li><strong>Exposici\u00f3n y vuelo de rapaces:<\/strong>\u00a0Conoce el papel de la cetrer\u00eda en la Edad Media a trav\u00e9s de una exposici\u00f3n did\u00e1ctica y una exhibici\u00f3n final de vuelo en libertad.<\/li>\n<li><strong>Exposici\u00f3n de instrumentos medievales<\/strong>:\u00a0Una muestra divulgativa para acercarse a los sonidos, ritmos e instrumentos de la corte del Rey Lobo.<\/li>\n<li><strong>Musicuentos en la corte del Rey Lobo:<\/strong>\u00a0Narraci\u00f3n musicalizada participativa ambientada en la corte andalus\u00ed de Ibn Mardanis.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong>Las actividades son gratuitas y no requieren inscripci\u00f3n<\/strong><\/span><\/p>\n<h4><span style=\"color: #993300;\"><strong>Programa<\/strong><\/span><\/h4>\n<ul>\n<li aria-level=\"1\">[17:30 &#8211; 21:00] Puertas abiertas y visitas guiadas cada hora\n<ul>\n<li aria-level=\"1\">Pases 18:00 | 19:00 | 20:00<\/li>\n<\/ul>\n<\/li>\n<li aria-level=\"1\">[18:00 &#8211; 20:00] Exposici\u00f3n de aves rapaces y explicaci\u00f3n de los ejemplares.<\/li>\n<li aria-level=\"1\">[18:00 &#8211; 20:00] Campamento de oficios medievales (actividad familiar)<\/li>\n<li aria-level=\"1\">[18:00 &#8211; 20:00] Exposici\u00f3n de instrumentos medievales<\/li>\n<li aria-level=\"1\">[19:30 &#8211; 20:00] Musicuentos en la corte del Rey Lobo<\/li>\n<li aria-level=\"1\">[20:00 &#8211; 20:45] Demostraci\u00f3n de vuelos en libertad (cetrer\u00eda)<\/li>\n<\/ul>\n<h4><span style=\"color: #993300;\"><strong>Detalles del evento<\/strong><\/span><\/h4>\n<ul>\n<li><strong>Fecha:<\/strong> S\u00e1bado 17\u00a0de mayo de 2025<\/li>\n<li><strong>Horario: <\/strong>De 17:30 a 21:00 horas<\/li>\n<li><strong>Ubicaci\u00f3n<\/strong>\u00a0<a href=\"https:\/\/maps.app.goo.gl\/7No2wiKnpXtW55Fq9\" data-cke-saved-href=\"https:\/\/maps.app.goo.gl\/7No2wiKnpXtW55Fq9\">Palacio de Ibn Mardanis (\u00abCastillejo\u00bb)<\/a><\/li>\n<li><a href=\"https:\/\/maps.app.goo.gl\/KPZUSLCUgjvEa2jK6\" data-cke-saved-href=\"https:\/\/maps.app.goo.gl\/KPZUSLCUgjvEa2jK6\">Zona de estacionamientos<\/a><\/li>\n<li><strong>Entrada libre\u00a0<\/strong><\/li>\n<\/ul>\n<h4><span style=\"color: #800000;\">Comparte<\/span><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6064\" src=\"https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026.jpg\" alt=\"\" width=\"1414\" height=\"2000\" srcset=\"https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026.jpg 1414w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026-212x300.jpg 212w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026-724x1024.jpg 724w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026-768x1086.jpg 768w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026-1086x1536.jpg 1086w, https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026-555x785.jpg 555w\" sizes=\"auto, (max-width: 1414px) 100vw, 1414px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p align=\"justify\">\n<p align=\"justify\">\n<p align=\"justify\">El Palacio Ibn Mardanis o Castillejo que se suma como escenario cultural con motivo del d\u00eda internacional de los museos, y acoger\u00e1 el s\u00e1bado de 17:30 a 21:00h una jornada llena de historia, cultura y diversi\u00f3n para sumergirse en la \u00e9poca de Ibn Mardanis, el c\u00e9lebre Rey Lobo, y descubrir &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/monteagudo.info\/web\/diamuseos-castillejo-2026\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":2,"featured_media":6064,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[108,100,176,144],"class_list":["post-6063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-castillejo","tag-cultura","tag-mardanis","tag-museo","nodate","item-wrap"],"jetpack_featured_media_url":"https:\/\/monteagudo.info\/web\/wp-content\/uploads\/2026\/05\/DiaMuseos_PalacioMardanis_2026.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/posts\/6063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/comments?post=6063"}],"version-history":[{"count":1,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/posts\/6063\/revisions"}],"predecessor-version":[{"id":6066,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/posts\/6063\/revisions\/6066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/media\/6064"}],"wp:attachment":[{"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/media?parent=6063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/categories?post=6063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monteagudo.info\/web\/wp-json\/wp\/v2\/tags?post=6063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}